{"id":3399,"date":"2015-10-23T19:34:17","date_gmt":"2015-10-23T22:34:17","guid":{"rendered":"http:\/\/coquetelmolotov.com.br\/novo\/?p=3399"},"modified":"2015-10-27T20:41:45","modified_gmt":"2015-10-27T23:41:45","slug":"fab-night-promove-bate-papo-sobre-o-festival-no-ar-coquetel-molotov","status":"publish","type":"post","link":"https:\/\/coquetelmolotov.com.br\/novo\/fab-night-promove-bate-papo-sobre-o-festival-no-ar-coquetel-molotov\/","title":{"rendered":"FAB NIGHT PROMOVE BATE PAPO SOBRE O FESTIVAL NO AR COQUETEL MOLOTOV"},"content":{"rendered":"<p>Na quarta (28), a partir das 18h, o Fab Lab Recife realiza mais uma Fab Night, tendo como tema o festival No Ar Coquetel Molotov. O evento \u00e9 aberto ao p\u00fablico e conta com um bate-papo sobre o projeto do Fab Lab para o festival e ainda cervejas e drinks, Chef Luli, ateli\u00ea de Dani Acioli e discotecagens com o DJ Igor Gazatti e o produtor Jarmeson de Lima.<\/p>\n<p>Wilton de Souza \u00e9 vendedor aut\u00f4nomo em eventos e vai participar do festival No Ar 2015 com produtos em um tabuleiro. Uma postagem dele no Facebook do festival gerou uma ades\u00e3o espont\u00e2nea do p\u00fablico em querer que ele participasse tamb\u00e9m do evento. <\/p>\n<p>Pensando numa forma de valorizar o trabalho do vendedor e destac\u00e1-lo em meio ao festival, o Fab Lab Recife deu um upgrade no tabuleiro de bomboniere do Sr. Wilton com um layout personalizado, melhorando o espa\u00e7o de disposi\u00e7\u00e3o dos produtos \u00e0 venda pra deix\u00e1-lo com a cara do Coquetel Molotov. Durante o bate-papo na Fab Night, a equipe vai finalizar a montagem do tabuleiro e entreg\u00e1-lo ao Sr. Wilton.<\/p>\n<p><strong>Inova\u00e7\u00e3o <\/strong>&#8211; O Fab Lab Recife \u00e9 um laborat\u00f3rio de fabrica\u00e7\u00e3o digital e uma plataforma de espa\u00e7o alternativo, aberto e colaborativo onde profissionais, estudantes e curiosos podem se reunir para conversar, e principalmente, materializar suas ideias. Um Fab Lab tem como objetivo democratizar o acesso \u00e0s ferramentas e m\u00e1quinas para permitir a inven\u00e7\u00e3o e as express\u00f5es pessoais. <\/p>\n<p>FAB NIGHT<br \/>\nESPECIAL NO AR COQUETEL MOLOTOV<br \/>\nQUARTA &#8211; 28 DE OUTUBRO &#8211; 18h<br \/>\nENDERE\u00c7O: Rua Dona Ada Vieira, 87 Casa Forte &#8211; Recife<br \/>\nABERTO AO P\u00daBLICO<br \/>\nMAIS INFORMA\u00c7\u00d5ES: <a href=\"https:\/\/www.facebook.com\/events\/501597926676758\/\" target=\"_blank\">https:\/\/www.facebook.com\/events\/501597926676758\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na quarta (28), a partir das 18h, o Fab Lab Recife realiza mais uma Fab Night, tendo como tema o festival No Ar Coquetel Molotov. O evento \u00e9 aberto ao p\u00fablico e conta com um bate-papo sobre o projeto do Fab Lab para o festival e ainda cervejas e drinks, Chef Luli, ateli\u00ea de Dani Acioli e discotecagens com o DJ Igor Gazatti e o produtor Jarmeson de Lima. Wilton de Souza \u00e9 vendedor aut\u00f4nomo em eventos e vai participar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[234,27,202,63],"class_list":["post-3399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-noticias","tag-234","tag-festival","tag-projeto","tag-recife"],"_links":{"self":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts\/3399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/comments?post=3399"}],"version-history":[{"count":0,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts\/3399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/media\/3400"}],"wp:attachment":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/media?parent=3399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/categories?post=3399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/tags?post=3399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}