{"id":3770,"date":"2016-09-09T13:41:24","date_gmt":"2016-09-09T16:41:24","guid":{"rendered":"http:\/\/coquetelmolotov.com.br\/novo\/?p=3770"},"modified":"2016-09-09T13:41:24","modified_gmt":"2016-09-09T16:41:24","slug":"diablo-angel-inicia-primeira-turne-pelo-nordeste","status":"publish","type":"post","link":"https:\/\/coquetelmolotov.com.br\/novo\/diablo-angel-inicia-primeira-turne-pelo-nordeste\/","title":{"rendered":"DIABLO ANGEL INICIA PRIMEIRA TURN\u00ca PELO NORDESTE"},"content":{"rendered":"<p>[soundcloud url=&#8221;https:\/\/api.soundcloud.com\/playlists\/209710046&#8243; params=&#8221;auto_play=false&#038;hide_related=false&#038;show_comments=true&#038;show_user=true&#038;show_reposts=false&#038;visual=true&#8221; width=&#8221;100%&#8221; height=&#8221;450&#8243; iframe=&#8221;true&#8221; \/]<\/p>\n<p>Com pouco mais de quatro meses de lan\u00e7amento do seu elogiado primeiro \u00e1lbum, o <strong>Fuzzled Mind<\/strong>, e mais de 10 shows, nesse per\u00edodo, entre a capital e o interior de Pernambuco, a Diablo Angel cai na estrada para primeira turn\u00ea da banda pelo Nordeste. <\/p>\n<p>\u201cEstamos nos articulando para tocar em todas as principais capitais do Nordeste\u201d, releva a vocalista e guitarrista, Kira Aderne. A turn\u00ea da banda tem in\u00edcio nesse m\u00eas de Outubro. No dia 14 de Outubro, a Diablo Angel se apresenta no Espa\u00e7o Mundo, em Jo\u00e3o Pessoa, Para\u00edba. E no dia seguinte, 15 de Outubro, o show \u00e9 no Espa\u00e7o Noronha, em Natal, Rio Grande do Norte.<\/p>\n<p>A Diablo Angel, que se divide entre as cidades de Caruaru, no Agreste, e Recife, tem dois anos de estrada. Formada por Kira Aderne, vocais e guitarra, T\u00e1rcio Luna na guitarra e Bruno Kiss, na bateria, a banda foi um dos grupos selecionados para o projeto Rubber Tracks, da Converse, em 2014, na cidade do Recife. Em 2015, a banda entrou em est\u00fadio para grava\u00e7\u00e3o do seu primeiro CD, o Fuzzled Mind, que foi gravado no L\u00e1 Em Casa Est\u00fadio com produ\u00e7\u00e3o de Henrique Arag\u00e3o. <\/p>\n<p><strong>Mais informa\u00e7\u00f5es<\/strong>: <a href=\"http:\/\/www.diabloangel.com\" target=\"_blank\">www.diabloangel.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[soundcloud url=&#8221;https:\/\/api.soundcloud.com\/playlists\/209710046&#8243; params=&#8221;auto_play=false&#038;hide_related=false&#038;show_comments=true&#038;show_user=true&#038;show_reposts=false&#038;visual=true&#8221; width=&#8221;100%&#8221; height=&#8221;450&#8243; iframe=&#8221;true&#8221; \/] Com pouco mais de quatro meses de lan\u00e7amento do seu elogiado primeiro \u00e1lbum, o Fuzzled Mind, e mais de 10 shows, nesse per\u00edodo, entre a capital e o interior de Pernambuco, a Diablo Angel cai na estrada para primeira turn\u00ea da banda pelo Nordeste. \u201cEstamos nos articulando para tocar em todas as principais capitais do Nordeste\u201d, releva a vocalista e guitarrista, Kira Aderne. A turn\u00ea da banda tem in\u00edcio nesse m\u00eas de Outubro. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[248,24,41],"class_list":["post-3770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-noticias","tag-nordeste","tag-show","tag-turne"],"_links":{"self":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts\/3770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/comments?post=3770"}],"version-history":[{"count":0,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts\/3770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/media\/3771"}],"wp:attachment":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/media?parent=3770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/categories?post=3770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/tags?post=3770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}