{"id":4282,"date":"2018-05-29T09:19:33","date_gmt":"2018-05-29T12:19:33","guid":{"rendered":"http:\/\/coquetelmolotov.com.br\/novo\/?p=4282"},"modified":"2018-05-29T09:46:00","modified_gmt":"2018-05-29T12:46:00","slug":"gestos-comemora-25-anos-com-super-festa-no-clube-atlantico","status":"publish","type":"post","link":"https:\/\/coquetelmolotov.com.br\/novo\/gestos-comemora-25-anos-com-super-festa-no-clube-atlantico\/","title":{"rendered":"GESTOS COMEMORA 25 ANOS COM SUPER FESTA NO CLUBE ATL\u00c2NTICO"},"content":{"rendered":"<p><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns='http:\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20800%20600'%3E%3C\/svg%3E\" data-lazy-src=\"http:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2018\/05\/SAMBAS-DE-ERASTO-2-e1527596342993.jpeg\" alt=\"\" width=\"800\" height=\"600\" class=\"zeen-lazy-load-base zeen-lazy-load aligncenter size-full wp-image-4283\" \/><noscript><img decoding=\"async\" src=\"http:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2018\/05\/SAMBAS-DE-ERASTO-2-e1527596342993.jpeg\" alt=\"\" width=\"800\" height=\"600\" class=\"aligncenter size-full wp-image-4283\" \/><\/noscript><\/p>\n<p>A Gestos \u2013 Soropositividade, Comunica\u00e7\u00e3o e G\u00eanero comemora seus 25 anos de ativismo e servi\u00e7os comunit\u00e1rios com uma grande festa beneficente no pr\u00f3ximo dia 1\u00ba de junho (sexta-feira). A celebra\u00e7\u00e3o ser\u00e1 no Clube Atl\u00e2ntico de Olinda, a partir das 19h30, com o apoio de v\u00e1rios parceiros da cultura. Teremos show do projeto Sambas de Erasto Vasconcelos (com Roger Man e Ganga Barreto) e do grupo Encantaria, DJs Lala K e Paulo Costa, M\u00f4nica Feij\u00f3, apresenta\u00e7\u00e3o especial de Christiane Falc\u00e3o e a presen\u00e7a do Som na Rural. Ser\u00e1 uma noite para dan\u00e7ar, com muita m\u00fasica, sorteios e bazar. <\/p>\n<p>Os artistas abriram m\u00e3o dos cach\u00eas em benef\u00edcio da Gestos. A entrada custa R$ 20 e todo o dinheiro arrecadado no evento ser\u00e1 revertido para a manuten\u00e7\u00e3o das atividades da ONG. Os ingressos est\u00e3o sendo vendidos na sede da Gestos (Rua dos M\u00e9dicis, 68, Boa Vista), no Bar Barrio (Olinda) e na Plataforma Sympla ().<\/p>\n<p>A festa est\u00e1 sendo organizada totalmente de maneira colaborativa e, al\u00e9m dos artistas (que n\u00e3o est\u00e3o cobrando cach\u00ea), conta com apoio de v\u00e1rias pessoas e empresas que doaram servi\u00e7os (seguran\u00e7a, banheiros qu\u00edmicos, impress\u00e3o de ingressos, cartazes, etc) e itens para serem sorteados durante o evento.<\/p>\n<p>Al\u00e9m dos pr\u00eamios, a Gestos conseguiu o apoio de artistas que doaram pe\u00e7as de seus acervos para um leil\u00e3o beneficente que ser\u00e1 realizado pela Gestos ainda este ano. Rinaldo Silva, Edson Menezes, Geg\u00ea Pedrosa, Dani Acioli, Carlos Pompeu, DMelo e Pedro Muniz doaram as obras que participar\u00e3o do leil\u00e3o.<\/p>\n<p>Durante todo o m\u00eas de junho, a ONG lembrar\u00e1 sua hist\u00f3ria, divulgando campanhas antigas, fotografias e depoimentos de pessoas que fazem parte dessa caminhada.<\/p>\n<p><strong>SAMBAS DE ERASTO<\/strong><\/p>\n<p>Pouco antes de seu falecimento, Erasto pede que seus sambas n\u00e3o se v\u00e3o juntamente com ele. Nasce h\u00e1 pouco mais de 8 meses o Sambas de Erasto, com composi\u00e7\u00f5es in\u00e9ditas feitas por ele na d\u00e9cada de 1970, durante viagem de navio para Nova York. Uma equipe de peso tem arranjado essas composi\u00e7\u00f5es. O grupo \u00e9 composto por Ganga Barreto na voz e percuss\u00e3o (Nan\u00e1 e Erasto Vasconcelos, Lia de Itamarac\u00e1, Circo Vivant, Think o fone \u2013 banda belga), Rogerman \u2013 voz (Bomsucesso Samba Clube, Eddie, Bai\u00e3o Polin\u00e1rio), Pablo Ferraz &#8211; percuss\u00e3o (Josildo S\u00e1, Tchida Africanu, Orquestra do Sucesso, Jorge Riba), Nino Silva \u2013 percuss\u00e3o (Josildo S\u00e1, Jorge Riba, Mestre Camar\u00e3o), Deco Trombone (Isaar, Ska Maria Pastora, Dj Dolores, Os Sert\u00f5es, Orquestra Santa Massa), Nelson Brederode \u2013 cavaco (Josildo S\u00e1, Mestre Camar\u00e3o, Beto do Bandolim, Claudionor Germano), Rafik Alfaia (Alfa man, Super Lage, Cassino Tropical, Querosene Jacar\u00e9) e Th\u00e9o Coutinho \u2013 viol\u00e3o (Conjunto Maravilha, Erasto Vasconcelos).<\/p>\n<p>O Sambas de Erasto ent\u00e3o \u00e9 criado para eternizar parte da obra do grande compositor e mostrar essa faceta sambista que muitos n\u00e3o conhecem. A continuidade de seu trabalho abrir\u00e1 uma oportunidade \u00fanica de ampliar o entendimento e a dimens\u00e3o de quem foi Erasto Vasconcelos viabilizando a entrada dele no mundo do samba onde n\u00e3o \u00e9 t\u00e3o conhecido, ampliando assim o n\u00famero de pessoas que v\u00e3o ter acesso as outras can\u00e7\u00f5es com estilos diferentes compostas por ele. A vitrine ser\u00e1 ampliada e a diversidade musical dele poder\u00e1 ser mais entendida e compreendida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Gestos \u2013 Soropositividade, Comunica\u00e7\u00e3o e G\u00eanero comemora seus 25 anos de ativismo e servi\u00e7os comunit\u00e1rios com uma grande festa beneficente no pr\u00f3ximo dia 1\u00ba de junho (sexta-feira). A celebra\u00e7\u00e3o ser\u00e1 no Clube Atl\u00e2ntico de Olinda, a partir das 19h30, com o apoio de v\u00e1rios parceiros da cultura. Teremos show do projeto Sambas de Erasto Vasconcelos (com Roger Man e Ganga Barreto) e do grupo Encantaria, DJs Lala K e Paulo Costa, M\u00f4nica Feij\u00f3, apresenta\u00e7\u00e3o especial de Christiane Falc\u00e3o e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[285,44,25,210,127,24],"class_list":["post-4282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque-noticias","tag-285","tag-agenda","tag-festa","tag-homenagem","tag-olinda","tag-show"],"_links":{"self":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts\/4282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/comments?post=4282"}],"version-history":[{"count":0,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts\/4282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/media\/4283"}],"wp:attachment":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/media?parent=4282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/categories?post=4282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/tags?post=4282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}