{"id":4621,"date":"2019-02-16T15:47:47","date_gmt":"2019-02-16T18:47:47","guid":{"rendered":"http:\/\/coquetelmolotov.com.br\/novo\/?p=4621"},"modified":"2019-03-18T10:46:20","modified_gmt":"2019-03-18T13:46:20","slug":"casa-tropical-estreia-no-carnaval-do-recife-com-curadoria-do-coquetel-molotov","status":"publish","type":"post","link":"https:\/\/coquetelmolotov.com.br\/novo\/casa-tropical-estreia-no-carnaval-do-recife-com-curadoria-do-coquetel-molotov\/","title":{"rendered":"CASA TROPICAL ESTREIA NO CARNAVAL DO RECIFE COM CURADORIA DO COQUETEL MOLOTOV"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns='http:\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20370%20247'%3E%3C\/svg%3E\" data-lazy-src=\"http:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02-1024x682.jpeg\" alt=\"\" class=\"zeen-lazy-load-base zeen-lazy-load wp-image-4622\"\/><noscript><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02-1024x682.jpeg\" alt=\"\" class=\"wp-image-4622\" srcset=\"https:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02-1024x682.jpeg 1024w, https:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02-300x200.jpeg 300w, https:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02-768x512.jpeg 768w, https:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02-365x243.jpeg 365w, https:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02-420x280.jpeg 420w, https:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02-150x100.jpeg 150w, https:\/\/coquetelmolotov.com.br\/novo\/wp-content\/uploads\/2019\/02\/CASA-TROPICAL-02.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n<p>Do domingo (3) at\u00e9 a ter\u00e7a-feira de Carnaval (5), a Casa Tropical, na sede da In Loco, em parceria com a Cervejaria Devassa, promove uma das melhores festas da folia pernambucana. O camarote ter\u00e1 capacidade para 400 convidados por dia e contar\u00e1 com open bar e open food para receber os foli\u00f5es. O casar\u00e3o abrir\u00e1 as portas a partir das 18h com programa\u00e7\u00e3o que inclui shows e DJs de todo Brasil, trazidos pela curadoria da Coquetel Molotov, al\u00e9m de uma das melhores vistas para palco do Polo Marco Zero. O line up completo da Casa Tropical ser\u00e1 divulgado em breve.<\/p>\n<p>&#8220;Somos uma empresa de tecnologia e estamos instalados no cora\u00e7\u00e3o de Recife. Nossa sede j\u00e1 abrigou um banco e os cofres intactos representam muito para n\u00f3s &#8211; eles s\u00e3o um s\u00edmbolo de privacidade que \u00e9 um dos compromissos da companhia. Al\u00e9m disso, temos uma vista privilegiada de Recife, no qual nosso time, clientes e pessoas que visitam a In Loco ficam encantados com a beleza da imensid\u00e3o da vis\u00e3o de nossas varandas e terra\u00e7o. Aproveitar toda essa hist\u00f3ria e espa\u00e7o para abrigar parte do Carnaval de Recife \u00e9 um enorme orgulho e prazer&#8221;, conta Andr\u00e9 Ferraz, CEO e cofundador da In Loco.<\/p>\n<p>O espa\u00e7o escolhido para o camarote Casa Tropical \u00e9 o palacete hist\u00f3rico situado entre as avenidas Alfredo Lisboa, Marqu\u00eas de Olinda e Rio Branco, no cora\u00e7\u00e3o do Bairro do Recife e que hoje abriga a sede da In Loco, empresa de tecnologia de localiza\u00e7\u00e3o. O pr\u00e9dio \u00e9 um dos mais imponentes exemplares da arquitetura ecl\u00e9tica da capital pernambucana. Al\u00e9m da vista privilegiada, onde \u00e9 poss\u00edvel ver dois dos mais importantes cart\u00f5es-postais do Recife, o Marco Zero e o Parque das Esculturas Francisco Brennand, o local oferece bebidas geladas, buffet especial e degusta\u00e7\u00e3o das guloseimas da Ben &amp; Jerry\u2019s.<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do domingo (3) at\u00e9 a ter\u00e7a-feira de Carnaval (5), a Casa Tropical, na sede da In Loco, em parceria com a Cervejaria Devassa, promove uma das melhores festas da folia pernambucana. O camarote ter\u00e1 capacidade para 400 convidados por dia e contar\u00e1 com open bar e open food para receber os foli\u00f5es. O casar\u00e3o abrir\u00e1 as portas a partir das 18h com programa\u00e7\u00e3o que inclui shows e DJs de todo Brasil, trazidos pela curadoria da Coquetel Molotov, al\u00e9m de uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[304,116,63],"class_list":["post-4621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-304","tag-carnaval","tag-recife"],"_links":{"self":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts\/4621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/comments?post=4621"}],"version-history":[{"count":0,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/posts\/4621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/media\/4622"}],"wp:attachment":[{"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/media?parent=4621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/categories?post=4621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coquetelmolotov.com.br\/novo\/wp-json\/wp\/v2\/tags?post=4621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}